{"id":75945,"date":"2016-08-26T11:22:00","date_gmt":"2016-08-26T11:22:00","guid":{"rendered":"https:\/\/santjoan.developersasapglobalsolution.com\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/"},"modified":"2016-08-26T11:22:00","modified_gmt":"2016-08-26T11:22:00","slug":"coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016","status":"publish","type":"post","link":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/","title":{"rendered":"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016."},"content":{"rendered":"<p class=\"MsoNormal\">\n<span style=\"font-size: 8pt; font-family: Verdana, sans-serif; background: #f6f6f6\">Com a novetat per a enguany<br \/>\nl&#8217;acte tornar\u00e0 a realitzar-se en l&#8217;empla\u00e7ament on tradicionalment es realitzava<br \/>\nfa anys, en la Pla\u00e7a de L&#8217;Ordana. A m\u00e9s de la part t\u00e8cnica, un dels motius pels<br \/>\nquals es trasllada a este lloc \u00e9s la capacitat d&#8217;albergar a les m\u00e9s de 1000<br \/>\npersones que acudixen a este acte tan emotiu i significatiu de les nostres<br \/>\nfestes majors, Festes en honor al Stmo. Crist de la Paz. Durant l&#8217;acte<br \/>\ncomptarem amb la col\u00b7laboraci\u00f3 de la Societat Musical La Paz i el Orfe\u00f3n San Juan i estar\u00e0 amenitzat per Valeria Le\u00f3n i la Compa\u00f1\u00eda Jade.<\/span>\n<\/p>\n<p class=\"MsoNormal\">\n<span style=\"font-size: 8pt; font-family: Verdana, sans-serif; background: #f6f6f6\">En l&#8217;esdeveniment despedirem les<br \/>\nnostres Reines i Dames majors 2015 Carmen Terol Caturla, Vanesa Mora P\u00e9rez i<br \/>\nAndrea Garc\u00eda Santos, aix\u00ed com a les infantils Llu\u00efa Marco B\u00f3, Danna Rus L\u00f3pez<br \/>\ni Andrea Soler Fern\u00e1ndez; I donarem pas a les Reines i Dames del Crist que<br \/>\nrepresentaran a Sant Joan durant tot enguany 2016. Les majors seran les<br \/>\nsenyoretes Stefany, Mar\u00eda i Ainara i infantils Nayla, Paula i Claudia.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"MsoNormal\">\n<span style=\"font-size: 8pt; font-family: Verdana, sans-serif; background: #f6f6f6\">Com a novetat per a enguany<br \/>\nl&#8217;acte tornar\u00e0 a realitzar-se en l&#8217;empla\u00e7ament on tradicionalment es realitzava<br \/>\nfa anys, en la Pla\u00e7a de L&#8217;Ordana. A m\u00e9s de la part t\u00e8cnica, un dels motius pels<br \/>\nquals es trasllada a este lloc \u00e9s la capacitat d&#8217;albergar a les m\u00e9s de 1000<br \/>\npersones que acudixen a este acte tan emotiu i significatiu de les nostres<br \/>\nfestes majors, Festes en honor al Stmo. Crist de la Paz.<\/p>\n","protected":false},"author":1,"featured_media":24600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"areas":[1001],"class_list":["post-75945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","areas-fiestas-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016. - Sant Joan d&#039;Alacant<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016. - Sant Joan d&#039;Alacant\" \/>\n<meta property=\"og:description\" content=\"Com a novetat per a enguany l&#039;acte tornar\u00e0 a realitzar-se en l&#039;empla\u00e7ament on tradicionalment es realitzava fa anys, en la Pla\u00e7a de L&#039;Ordana. A m\u00e9s de la part t\u00e8cnica, un dels motius pels quals es trasllada a este lloc \u00e9s la capacitat d&#039;albergar a les m\u00e9s de 1000 persones que acudixen a este acte tan emotiu i significatiu de les nostres festes majors, Festes en honor al Stmo. Crist de la Paz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Sant Joan d&#039;Alacant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/santjoandalacant\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-26T11:22:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.santjoandalacant.es\/wp-content\/uploads\/2017\/06\/webcartelcoronacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"258\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"6tems\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"6tems\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/\"},\"author\":{\"name\":\"6tems\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#\\\/schema\\\/person\\\/74b89bc7b26e6edafb76cd69420cd790\"},\"headline\":\"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016.\",\"datePublished\":\"2016-08-26T11:22:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/\"},\"wordCount\":199,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.santjoandalacant.es\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/webcartelcoronacion.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"va\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/\",\"url\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/\",\"name\":\"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016. - Sant Joan d&#039;Alacant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.santjoandalacant.es\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/webcartelcoronacion.jpg\",\"datePublished\":\"2016-08-26T11:22:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/#breadcrumb\"},\"inLanguage\":\"va\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.santjoandalacant.es\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/webcartelcoronacion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.santjoandalacant.es\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/webcartelcoronacion.jpg\",\"width\":258,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/\",\"name\":\"Sant Joan d'Alacant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#organization\",\"name\":\"Sant Joan d'Alacant\",\"url\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.santjoandalacant.es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logoSJ.png\",\"contentUrl\":\"https:\\\/\\\/www.santjoandalacant.es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logoSJ.png\",\"width\":198,\"height\":253,\"caption\":\"Sant Joan d'Alacant\"},\"image\":{\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/santjoandalacant\\\/\",\"https:\\\/\\\/www.instagram.com\\\/santjoandalacant\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/santjoandalacant\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/#\\\/schema\\\/person\\\/74b89bc7b26e6edafb76cd69420cd790\",\"name\":\"6tems\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c939d9bf86da56568327e5d52b159d089efba17cde140c49884e3fe77ef9c66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c939d9bf86da56568327e5d52b159d089efba17cde140c49884e3fe77ef9c66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c939d9bf86da56568327e5d52b159d089efba17cde140c49884e3fe77ef9c66?s=96&d=mm&r=g\",\"caption\":\"6tems\"},\"sameAs\":[\"https:\\\/\\\/www.santjoandalacant.es\"],\"url\":\"https:\\\/\\\/www.santjoandalacant.es\\\/ca\\\/author\\\/adminasap\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016. - Sant Joan d&#039;Alacant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/","og_locale":"en_US","og_type":"article","og_title":"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016. - Sant Joan d&#039;Alacant","og_description":"Com a novetat per a enguany l'acte tornar\u00e0 a realitzar-se en l'empla\u00e7ament on tradicionalment es realitzava fa anys, en la Pla\u00e7a de L'Ordana. A m\u00e9s de la part t\u00e8cnica, un dels motius pels quals es trasllada a este lloc \u00e9s la capacitat d'albergar a les m\u00e9s de 1000 persones que acudixen a este acte tan emotiu i significatiu de les nostres festes majors, Festes en honor al Stmo. Crist de la Paz.","og_url":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/","og_site_name":"Sant Joan d&#039;Alacant","article_publisher":"https:\/\/www.facebook.com\/santjoandalacant\/","article_published_time":"2016-08-26T11:22:00+00:00","og_image":[{"width":258,"height":365,"url":"https:\/\/www.santjoandalacant.es\/wp-content\/uploads\/2017\/06\/webcartelcoronacion.jpg","type":"image\/jpeg"}],"author":"6tems","twitter_card":"summary_large_image","twitter_misc":{"Written by":"6tems","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/#article","isPartOf":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/"},"author":{"name":"6tems","@id":"https:\/\/www.santjoandalacant.es\/ca\/#\/schema\/person\/74b89bc7b26e6edafb76cd69420cd790"},"headline":"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016.","datePublished":"2016-08-26T11:22:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/"},"wordCount":199,"commentCount":0,"publisher":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/#organization"},"image":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.santjoandalacant.es\/wp-content\/uploads\/2017\/06\/webcartelcoronacion.jpg","articleSection":["Sin categorizar"],"inLanguage":"va","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/","url":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/","name":"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016. - Sant Joan d&#039;Alacant","isPartOf":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/#primaryimage"},"image":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.santjoandalacant.es\/wp-content\/uploads\/2017\/06\/webcartelcoronacion.jpg","datePublished":"2016-08-26T11:22:00+00:00","breadcrumb":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/#breadcrumb"},"inLanguage":"va","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/"]}]},{"@type":"ImageObject","inLanguage":"va","@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/#primaryimage","url":"https:\/\/www.santjoandalacant.es\/wp-content\/uploads\/2017\/06\/webcartelcoronacion.jpg","contentUrl":"https:\/\/www.santjoandalacant.es\/wp-content\/uploads\/2017\/06\/webcartelcoronacion.jpg","width":258,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/www.santjoandalacant.es\/ca\/coronacio-reines-i-dames-majors-i-infantils-del-stmo-crist-de-la-paz-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.santjoandalacant.es\/ca\/"},{"@type":"ListItem","position":2,"name":"CORONACI\u00d3 REINES I DAMES MAJORS I INFANTILS DEL STMO. CRIST DE LA PAZ 2016."}]},{"@type":"WebSite","@id":"https:\/\/www.santjoandalacant.es\/ca\/#website","url":"https:\/\/www.santjoandalacant.es\/ca\/","name":"Sant Joan d'Alacant","description":"","publisher":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.santjoandalacant.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va"},{"@type":"Organization","@id":"https:\/\/www.santjoandalacant.es\/ca\/#organization","name":"Sant Joan d'Alacant","url":"https:\/\/www.santjoandalacant.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"va","@id":"https:\/\/www.santjoandalacant.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.santjoandalacant.es\/wp-content\/uploads\/2023\/08\/logoSJ.png","contentUrl":"https:\/\/www.santjoandalacant.es\/wp-content\/uploads\/2023\/08\/logoSJ.png","width":198,"height":253,"caption":"Sant Joan d'Alacant"},"image":{"@id":"https:\/\/www.santjoandalacant.es\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/santjoandalacant\/","https:\/\/www.instagram.com\/santjoandalacant\/","https:\/\/www.youtube.com\/user\/santjoandalacant"]},{"@type":"Person","@id":"https:\/\/www.santjoandalacant.es\/ca\/#\/schema\/person\/74b89bc7b26e6edafb76cd69420cd790","name":"6tems","image":{"@type":"ImageObject","inLanguage":"va","@id":"https:\/\/secure.gravatar.com\/avatar\/1c939d9bf86da56568327e5d52b159d089efba17cde140c49884e3fe77ef9c66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c939d9bf86da56568327e5d52b159d089efba17cde140c49884e3fe77ef9c66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c939d9bf86da56568327e5d52b159d089efba17cde140c49884e3fe77ef9c66?s=96&d=mm&r=g","caption":"6tems"},"sameAs":["https:\/\/www.santjoandalacant.es"],"url":"https:\/\/www.santjoandalacant.es\/ca\/author\/adminasap\/"}]}},"_links":{"self":[{"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/posts\/75945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/comments?post=75945"}],"version-history":[{"count":0,"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/posts\/75945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/media\/24600"}],"wp:attachment":[{"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/media?parent=75945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/categories?post=75945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/tags?post=75945"},{"taxonomy":"areas","embeddable":true,"href":"https:\/\/www.santjoandalacant.es\/ca\/wp-json\/wp\/v2\/areas?post=75945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}